{"id":5532,"date":"2023-07-26T03:53:19","date_gmt":"2023-07-26T01:53:19","guid":{"rendered":"https:\/\/test.swingsy.fr\/?page_id=5532"},"modified":"2025-06-18T17:14:59","modified_gmt":"2025-06-18T15:14:59","slug":"destinations-libertines","status":"publish","type":"page","link":"https:\/\/swingsytravel.com\/en\/destinations-libertines\/","title":{"rendered":"Destinations libertines"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5532\" class=\"elementor elementor-5532\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a60ae96 e-flex e-con-boxed e-con e-parent\" data-id=\"a60ae96\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c86df1a elementor-widget elementor-widget-spacer\" data-id=\"c86df1a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf09e88 elementor-widget elementor-widget-heading\" data-id=\"cf09e88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9couvrez nos destinations libertines<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7edb930 elementor-widget elementor-widget-spacer\" data-id=\"7edb930\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5257c01 elementor-widget elementor-widget-text-editor\" data-id=\"5257c01\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Swingsy cr\u00e9e ses propres voyages mais s&#8217;associe aussi \u00e0 de nombreux partenaires \u00e0 travers le monde pour vous faire voyager dans tous les meilleurs lieux pour des vacances libertines. Des lieux de f\u00eates, des lieux plus adapt\u00e9s \u00e0 la d\u00e9tente, il y en a pour tous les go\u00fbts.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d2fc26 elementor-widget elementor-widget-spacer\" data-id=\"4d2fc26\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b688913 e-flex e-con-boxed e-con e-parent\" data-id=\"b688913\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cb83db4 e-con-full e-flex e-con e-child\" data-id=\"cb83db4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-334b931 elementor-widget elementor-widget-image\" data-id=\"334b931\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/10\/Limosuine-lib-.jpg\" class=\"attachment-large size-large wp-image-5691\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8bb92d elementor-widget elementor-widget-spacer\" data-id=\"b8bb92d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6de803 elementor-widget elementor-widget-heading\" data-id=\"e6de803\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Limousine by night au c\u0153ur de Paris !<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04f561a elementor-widget elementor-widget-text-editor\" data-id=\"04f561a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00e0 partir de 380\u20ac<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d6324 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c2d6324\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/swingsytravel.com\/en\/product\/limousine-by-night-au-coeur-de-paris\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d399b4 e-con-full e-flex e-con e-child\" data-id=\"7d399b4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b29feae elementor-widget elementor-widget-image\" data-id=\"b29feae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"726\" height=\"1024\" src=\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2025\/06\/Vibes.jpg\" class=\"attachment-large size-large wp-image-6639\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfa0320 elementor-widget elementor-widget-spacer\" data-id=\"cfa0320\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f3d43e elementor-widget elementor-widget-heading\" data-id=\"8f3d43e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le Vibes Resort, r\u00e9sidence de luxe au Cap d\u2019Agde<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68679a5 elementor-widget elementor-widget-text-editor\" data-id=\"68679a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00e0 partir de 260 400 \u20ac<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29a4379 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"29a4379\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/swingsytravel.com\/en\/product\/investissement-vibes-resort-cap-agde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49d9ca1 e-flex e-con-boxed e-con e-parent\" data-id=\"49d9ca1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-11a36ee e-con-full e-flex e-con e-child\" data-id=\"11a36ee\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e42c4c1 elementor-widget elementor-widget-image\" data-id=\"e42c4c1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/09\/hedo.jpg\" class=\"attachment-large size-large wp-image-5694\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47958ab elementor-widget elementor-widget-spacer\" data-id=\"47958ab\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a7a2b4 elementor-widget elementor-widget-heading\" data-id=\"8a7a2b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hedonism II\n(N\u00e9gril, Jama\u00efque)\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1684ae2 elementor-widget elementor-widget-text-editor\" data-id=\"1684ae2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00e0 partir de 400\u20ac<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22125a8 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"22125a8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/swingsytravel.com\/en\/product\/hedonism-ii-jamaique\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e861ef6 e-con-full e-flex e-con e-child\" data-id=\"e861ef6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea3cbdb elementor-widget elementor-widget-image\" data-id=\"ea3cbdb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"990\" src=\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/09\/desire-pearl-cancun.jpg\" class=\"attachment-large size-large wp-image-5640\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd216a8 elementor-widget elementor-widget-spacer\" data-id=\"bd216a8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12765e7 elementor-widget elementor-widget-heading\" data-id=\"12765e7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Desire Pearl Maya Resort - Mexique - Cancun<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f224112 elementor-widget elementor-widget-text-editor\" data-id=\"f224112\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00e0 partir de 350\u20ac<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5365f49 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"5365f49\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/swingsytravel.com\/en\/product\/desire-pearl-maya-resort-mexique-cancun\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fc1903 e-con-full e-flex e-con e-child\" data-id=\"3fc1903\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6970ad7 elementor-widget elementor-widget-image\" data-id=\"6970ad7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"990\" src=\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/09\/Desire-Resort-Spa-Riviera-Maya.jpg\" class=\"attachment-large size-large wp-image-5581\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07d1873 elementor-widget elementor-widget-spacer\" data-id=\"07d1873\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d786737 elementor-widget elementor-widget-heading\" data-id=\"d786737\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Desire Resort &amp; Spa Riviera Maya - Mexique\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35f935a elementor-widget elementor-widget-text-editor\" data-id=\"35f935a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00e0 partir de 350\u20ac<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef7af9a elementor-align-left elementor-widget elementor-widget-button\" data-id=\"ef7af9a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/swingsytravel.com\/en\/product\/desire-resort-spa-riviera-maya-mexique-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9f7da3 e-con-full e-flex e-con e-child\" data-id=\"e9f7da3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-962d57b elementor-widget elementor-widget-image\" data-id=\"962d57b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"1024\" src=\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/12\/Miches-Re\u0301publique-Dominicaine.jpg\" class=\"attachment-large size-large wp-image-6198\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de82a34 elementor-widget elementor-widget-spacer\" data-id=\"de82a34\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-145928b elementor-widget elementor-widget-heading\" data-id=\"145928b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Temptation Miches Resort - R\u00e9publique Dominicaine\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edeb864 elementor-widget elementor-widget-text-editor\" data-id=\"edeb864\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00e0 partir de 350\u20ac<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfe4e0a elementor-align-left elementor-widget elementor-widget-button\" data-id=\"dfe4e0a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/swingsytravel.com\/en\/product\/temptation-miches-resort-republique-dominicaine\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez nos destinations libertines Swingsy cr\u00e9e ses propres voyages mais s&#8217;associe aussi \u00e0 de nombreux partenaires \u00e0 travers le monde pour vous faire voyager dans tous les meilleurs lieux pour des vacances libertines. Des lieux de f\u00eates, des lieux plus adapt\u00e9s \u00e0 la d\u00e9tente, il y en a pour tous les go\u00fbts.\u00a0 Limousine by night [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5532","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Destinations libertines - Swingsy Travel<\/title>\n<meta name=\"description\" content=\"Destinations libertines en France et ailleurs, voyages sur mesure pour couples libertins, complexes hoteliers, maisons d&#039;h\u00f4tes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swingsytravel.com\/en\/destinations-libertines\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Destinations libertines - Swingsy Travel\" \/>\n<meta property=\"og:description\" content=\"Destinations libertines en France et ailleurs, voyages sur mesure pour couples libertins, complexes hoteliers, maisons d&#039;h\u00f4tes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swingsytravel.com\/en\/destinations-libertines\/\" \/>\n<meta property=\"og:site_name\" content=\"Swingsy Travel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swingsyfrance\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T15:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/10\/Limosuine-lib-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"1671\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SwingsyFrance\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swingsytravel.com\/destinations-libertines\/\",\"url\":\"https:\/\/swingsytravel.com\/destinations-libertines\/\",\"name\":\"Destinations libertines - Swingsy Travel\",\"isPartOf\":{\"@id\":\"https:\/\/swingsytravel.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/swingsytravel.com\/destinations-libertines\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/swingsytravel.com\/destinations-libertines\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/10\/Limosuine-lib-.jpg\",\"datePublished\":\"2023-07-26T01:53:19+00:00\",\"dateModified\":\"2025-06-18T15:14:59+00:00\",\"description\":\"Destinations libertines en France et ailleurs, voyages sur mesure pour couples libertins, complexes hoteliers, maisons d'h\u00f4tes.\",\"breadcrumb\":{\"@id\":\"https:\/\/swingsytravel.com\/destinations-libertines\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swingsytravel.com\/destinations-libertines\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/swingsytravel.com\/destinations-libertines\/#primaryimage\",\"url\":\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/10\/Limosuine-lib-.jpg\",\"contentUrl\":\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/10\/Limosuine-lib-.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swingsytravel.com\/destinations-libertines\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/swingsytravel.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destinations libertines\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swingsytravel.com\/#website\",\"url\":\"https:\/\/swingsytravel.com\/\",\"name\":\"Swingsy Travel\",\"description\":\"Orgasmisateur de voyage\",\"publisher\":{\"@id\":\"https:\/\/swingsytravel.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swingsytravel.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/swingsytravel.com\/#organization\",\"name\":\"Swingsy Travel\",\"url\":\"https:\/\/swingsytravel.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/swingsytravel.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2020\/02\/350x100.png\",\"contentUrl\":\"https:\/\/swingsytravel.com\/wp-content\/uploads\/2020\/02\/350x100.png\",\"width\":350,\"height\":100,\"caption\":\"Swingsy Travel\"},\"image\":{\"@id\":\"https:\/\/swingsytravel.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/swingsyfrance\/\",\"https:\/\/x.com\/SwingsyFrance\",\"https:\/\/www.instagram.com\/swingsy.insta\/\",\"https:\/\/www.youtube.com\/channel\/UC3HEecp9VYMXuie9yXm_6fA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Destinations libertines - Swingsy Travel","description":"Destinations libertines en France et ailleurs, voyages sur mesure pour couples libertins, complexes hoteliers, maisons d'h\u00f4tes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swingsytravel.com\/en\/destinations-libertines\/","og_locale":"en_US","og_type":"article","og_title":"Destinations libertines - Swingsy Travel","og_description":"Destinations libertines en France et ailleurs, voyages sur mesure pour couples libertins, complexes hoteliers, maisons d'h\u00f4tes.","og_url":"https:\/\/swingsytravel.com\/en\/destinations-libertines\/","og_site_name":"Swingsy Travel","article_publisher":"https:\/\/www.facebook.com\/swingsyfrance\/","article_modified_time":"2025-06-18T15:14:59+00:00","og_image":[{"width":1181,"height":1671,"url":"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/10\/Limosuine-lib-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SwingsyFrance","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swingsytravel.com\/destinations-libertines\/","url":"https:\/\/swingsytravel.com\/destinations-libertines\/","name":"Destinations libertines - Swingsy Travel","isPartOf":{"@id":"https:\/\/swingsytravel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swingsytravel.com\/destinations-libertines\/#primaryimage"},"image":{"@id":"https:\/\/swingsytravel.com\/destinations-libertines\/#primaryimage"},"thumbnailUrl":"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/10\/Limosuine-lib-.jpg","datePublished":"2023-07-26T01:53:19+00:00","dateModified":"2025-06-18T15:14:59+00:00","description":"Destinations libertines en France et ailleurs, voyages sur mesure pour couples libertins, complexes hoteliers, maisons d'h\u00f4tes.","breadcrumb":{"@id":"https:\/\/swingsytravel.com\/destinations-libertines\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swingsytravel.com\/destinations-libertines\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/swingsytravel.com\/destinations-libertines\/#primaryimage","url":"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/10\/Limosuine-lib-.jpg","contentUrl":"https:\/\/swingsytravel.com\/wp-content\/uploads\/2023\/10\/Limosuine-lib-.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/swingsytravel.com\/destinations-libertines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swingsytravel.com\/"},{"@type":"ListItem","position":2,"name":"Destinations libertines"}]},{"@type":"WebSite","@id":"https:\/\/swingsytravel.com\/#website","url":"https:\/\/swingsytravel.com\/","name":"Swingsy Travel","description":"Orgasmisateur de voyage","publisher":{"@id":"https:\/\/swingsytravel.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swingsytravel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/swingsytravel.com\/#organization","name":"Swingsy Travel","url":"https:\/\/swingsytravel.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/swingsytravel.com\/#\/schema\/logo\/image\/","url":"https:\/\/swingsytravel.com\/wp-content\/uploads\/2020\/02\/350x100.png","contentUrl":"https:\/\/swingsytravel.com\/wp-content\/uploads\/2020\/02\/350x100.png","width":350,"height":100,"caption":"Swingsy Travel"},"image":{"@id":"https:\/\/swingsytravel.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swingsyfrance\/","https:\/\/x.com\/SwingsyFrance","https:\/\/www.instagram.com\/swingsy.insta\/","https:\/\/www.youtube.com\/channel\/UC3HEecp9VYMXuie9yXm_6fA"]}]}},"_links":{"self":[{"href":"https:\/\/swingsytravel.com\/en\/wp-json\/wp\/v2\/pages\/5532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swingsytravel.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swingsytravel.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swingsytravel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swingsytravel.com\/en\/wp-json\/wp\/v2\/comments?post=5532"}],"version-history":[{"count":110,"href":"https:\/\/swingsytravel.com\/en\/wp-json\/wp\/v2\/pages\/5532\/revisions"}],"predecessor-version":[{"id":6658,"href":"https:\/\/swingsytravel.com\/en\/wp-json\/wp\/v2\/pages\/5532\/revisions\/6658"}],"wp:attachment":[{"href":"https:\/\/swingsytravel.com\/en\/wp-json\/wp\/v2\/media?parent=5532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}